{"id":4696,"date":"2022-03-03T15:20:00","date_gmt":"2022-03-03T14:20:00","guid":{"rendered":"https:\/\/lgd.com.pl\/?p=4696"},"modified":"2022-03-07T15:22:43","modified_gmt":"2022-03-07T14:22:43","slug":"rozstrzygniecie-zapytania-ofertowego-nr-2-2022","status":"publish","type":"post","link":"https:\/\/lgd.com.pl\/archiwum24\/rozstrzygniecie-zapytania-ofertowego-nr-2-2022\/","title":{"rendered":"Rozstrzygni\u0119cie zapytania ofertowego nr 2\/2022"},"content":{"rendered":"\n<div class=\"wp-block-file\"><a href=\"https:\/\/lgd.com.pl\/archiwum24\/wp-content\/uploads\/2022\/03\/rozstrzygniecie-2-mat-biur-2022.pdf\">Rozstrzygni\u0119cie zapytania 2\/2022<\/a><a href=\"https:\/\/lgd.com.pl\/archiwum24\/wp-content\/uploads\/2022\/03\/rozstrzygniecie-2-mat-biur-2022.pdf\" class=\"wp-block-file__button\" download>Pobierz<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"Rozstrzygni\u0119cie zapytania 2\/2022Pobierz","protected":false},"author":2,"featured_media":4457,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"_links":{"self":[{"href":"https:\/\/lgd.com.pl\/archiwum24\/wp-json\/wp\/v2\/posts\/4696"}],"collection":[{"href":"https:\/\/lgd.com.pl\/archiwum24\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lgd.com.pl\/archiwum24\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lgd.com.pl\/archiwum24\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lgd.com.pl\/archiwum24\/wp-json\/wp\/v2\/comments?post=4696"}],"version-history":[{"count":1,"href":"https:\/\/lgd.com.pl\/archiwum24\/wp-json\/wp\/v2\/posts\/4696\/revisions"}],"predecessor-version":[{"id":4698,"href":"https:\/\/lgd.com.pl\/archiwum24\/wp-json\/wp\/v2\/posts\/4696\/revisions\/4698"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lgd.com.pl\/archiwum24\/wp-json\/wp\/v2\/media\/4457"}],"wp:attachment":[{"href":"https:\/\/lgd.com.pl\/archiwum24\/wp-json\/wp\/v2\/media?parent=4696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lgd.com.pl\/archiwum24\/wp-json\/wp\/v2\/categories?post=4696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lgd.com.pl\/archiwum24\/wp-json\/wp\/v2\/tags?post=4696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}