{"id":4670,"date":"2022-02-23T12:16:39","date_gmt":"2022-02-23T11:16:39","guid":{"rendered":"https:\/\/lgd.com.pl\/?p=4670"},"modified":"2022-02-23T12:16:41","modified_gmt":"2022-02-23T11:16:41","slug":"rozstrzygniecie-zapytania-ofertowego-nr-1-2022","status":"publish","type":"post","link":"https:\/\/lgd.com.pl\/archiwum24\/rozstrzygniecie-zapytania-ofertowego-nr-1-2022\/","title":{"rendered":"Rozstrzygni\u0119cie zapytania ofertowego nr 1\/2022"},"content":{"rendered":"\n<div class=\"wp-block-file\"><a href=\"https:\/\/lgd.com.pl\/archiwum24\/wp-content\/uploads\/2022\/02\/rozstrzygniecie-1-mat-biur.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Rozstrzygni\u0119cie zapytanie nr 1\/2022<\/a><a href=\"https:\/\/lgd.com.pl\/archiwum24\/wp-content\/uploads\/2022\/02\/rozstrzygniecie-1-mat-biur.pdf\" class=\"wp-block-file__button\" download>Pobierz<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"Rozstrzygni\u0119cie zapytanie nr 1\/2022Pobierz","protected":false},"author":2,"featured_media":4457,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"_links":{"self":[{"href":"https:\/\/lgd.com.pl\/archiwum24\/wp-json\/wp\/v2\/posts\/4670"}],"collection":[{"href":"https:\/\/lgd.com.pl\/archiwum24\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lgd.com.pl\/archiwum24\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lgd.com.pl\/archiwum24\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lgd.com.pl\/archiwum24\/wp-json\/wp\/v2\/comments?post=4670"}],"version-history":[{"count":1,"href":"https:\/\/lgd.com.pl\/archiwum24\/wp-json\/wp\/v2\/posts\/4670\/revisions"}],"predecessor-version":[{"id":4672,"href":"https:\/\/lgd.com.pl\/archiwum24\/wp-json\/wp\/v2\/posts\/4670\/revisions\/4672"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lgd.com.pl\/archiwum24\/wp-json\/wp\/v2\/media\/4457"}],"wp:attachment":[{"href":"https:\/\/lgd.com.pl\/archiwum24\/wp-json\/wp\/v2\/media?parent=4670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lgd.com.pl\/archiwum24\/wp-json\/wp\/v2\/categories?post=4670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lgd.com.pl\/archiwum24\/wp-json\/wp\/v2\/tags?post=4670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}